{"id":4967,"date":"2026-05-27T10:56:22","date_gmt":"2026-05-27T08:56:22","guid":{"rendered":"https:\/\/www.diocesi.torino.it\/salute\/?p=4967"},"modified":"2026-07-08T09:27:22","modified_gmt":"2026-07-08T07:27:22","slug":"lu-me-accompagnamento-e-ascolto-nel-lutto-e-nella-sofferenza-mentale","status":"publish","type":"post","link":"https:\/\/www.diocesi.torino.it\/salute\/lu-me-accompagnamento-e-ascolto-nel-lutto-e-nella-sofferenza-mentale\/","title":{"rendered":"Lu.Me. Accompagnamento e Ascolto nel Lutto e nella Sofferenza Mentale"},"content":{"rendered":"<div>Sono due i servizi realizzati in collaborazione con i Tavoli diocesani per la pastorale del lutto e per la salute mentale.<\/div>\n<div><\/div>\n<div><b>Accompagnamento ed Ascolto nel lutto<\/b><\/div>\n<div>Il servizio \u00e8 rivolto a tutti coloro che affrontano situazioni di lutto e che necessitano di qualche forma di aiuto e supporto relazionale per elaborare la perdita e superare le fasi pi\u00f9 acute di sofferenza. Il servizio propone attivit\u00e0 di ascolto ed accompagnamento sia telefonico che di persona, effettuato da personale volontario appositamente formato.<\/div>\n<div>Le attivit\u00e0 proposte riguardano anche l\u2019organizzazione di gruppi di auto-mutuo aiuto, gestiti da esperti.<\/div>\n<div style=\"margin: 0cm 24.25pt 0pt 0cm; text-align: justify;\"><\/div>\n<div style=\"margin: 0cm 24.25pt 0pt 0cm; text-align: justify;\"><b>Accompagnamento ed Ascolto nella sofferenza mentale.<\/b><\/div>\n<div style=\"margin: 0cm 24.25pt 0pt 0cm; text-align: justify;\">Il servizio \u00e8 rivolto a coloro che affrontano casi (in parrocchia, parenti, amici, conoscenti, colleghi etc.) di sofferenza mentale, oppure ne sono direttamente interessati. L&#8217;attivit\u00e0 svolta verte essenzialmente sull&#8217;ascolto e l&#8217;orientamento, in particolare per quanto concerne i rapporti con i centri di salute mentale ed i servizi sociali. Le attivit\u00e0\u00a0sono svolte in orari prefissati, telefonicamente o di persona\u00a0&#8211; in questo caso su appuntamento &#8211; e sono\u00a0effettuate da personale volontario appositamente formato.<\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div>per contatti: 011.51.56.362 oppure salute.progetti@diocesi.to.it<\/div>\n<div style=\"margin: 0cm 24.25pt 0pt 0cm; text-align: justify;\"><\/div>\n<div style=\"margin: 0cm 24.25pt 0pt 0cm; text-align: justify;\"><span style=\"font-size: inherit;\">I servizi di accompagnamento ed ascolto sono gratuiti.<\/span><\/div>\n<div><\/div>\n<div>Pi\u00f9 sotto, \u00e8 possibile scaricare pieghevole del servizio di accompagnamento e ascolto nel Lutto<\/div>\n<hr class=\"wpba_attachment_hr\"><div id='wpba_attachment_list' class='wpba wpba-wrap'>\n<ul class='wpba-attachment-list unstyled'><li id='wpba_attachment_list_5618' class='wpba-list-item pull-left'><img src='https:\/\/www.diocesi.torino.it\/salute\/wp-content\/themes\/wp-starter-so\/icons\/document.png' width='16' height='20' class='wpba-icon pull-left'><a href='https:\/\/www.diocesi.torino.it\/salute\/wp-content\/uploads\/sites\/9\/2026\/05\/PIEGHEVOLE-TAVOLO-DIOCESANO-LUTTO-2026.pdf' title='PIEGHEVOLE TAVOLO-DIOCESANO-LUTTO-2026' class='wpba-link pull-left' target=\"_blank\">PIEGHEVOLE TAVOLO-DIOCESANO-LUTTO-2026<\/a><\/li>\n<\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sono due i servizi realizzati in collaborazione con i Tavoli diocesani per la pastorale del lutto e per la salute mentale. Accompagnamento ed Ascolto nel lutto Il servizio \u00e8 rivolto a tutti coloro che affrontano situazioni di lutto e che necessitano di qualche forma di aiuto e supporto relazionale per elaborare la perdita e superare le fasi pi\u00f9 acute di sofferenza. Il servizio propone attivit\u00e0 &hellip; <a href=\"https:\/\/www.diocesi.torino.it\/salute\/lu-me-accompagnamento-e-ascolto-nel-lutto-e-nella-sofferenza-mentale\/\" class=\"more-link\">Continua a leggere <span class=\"screen-reader-text\"><\/span> <span class=\"meta-nav\">&raquo;<\/span><\/a><\/p>\n","protected":false},"author":11,"featured_media":1318,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ip_address":"","user_agent":"","level":"","revision":"","cookie_id":"","page_referer":"","html_form":"","_expiration-date-status":"","_expiration-date":0,"_expiration-date-type":"","_expiration-date-categories":[],"_expiration-date-options":[]},"categories":[94,95],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lu.Me. Accompagnamento e Ascolto nel Lutto e nella Sofferenza Mentale - Pastorale della SALUTE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diocesi.torino.it\/salute\/lu-me-accompagnamento-e-ascolto-nel-lutto-e-nella-sofferenza-mentale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lu.Me. Accompagnamento e Ascolto nel Lutto e nella Sofferenza Mentale - Pastorale della SALUTE\" \/>\n<meta property=\"og:description\" content=\"Sono due i servizi realizzati in collaborazione con i Tavoli diocesani per la pastorale del lutto e per la salute mentale. Accompagnamento ed Ascolto nel lutto Il servizio \u00e8 rivolto a tutti coloro che affrontano situazioni di lutto e che necessitano di qualche forma di aiuto e supporto relazionale per elaborare la perdita e superare le fasi pi\u00f9 acute di sofferenza. Il servizio propone attivit\u00e0 &hellip; Continua a leggere &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diocesi.torino.it\/salute\/lu-me-accompagnamento-e-ascolto-nel-lutto-e-nella-sofferenza-mentale\/\" \/>\n<meta property=\"og:site_name\" content=\"Pastorale della SALUTE\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-27T08:56:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T07:27:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diocesi.torino.it\/salute\/wp-content\/uploads\/sites\/9\/2017\/09\/Lume.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"270\" \/>\n\t<meta property=\"og:image:height\" content=\"270\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ivanraimondi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ivanraimondi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.diocesi.torino.it\/salute\/lu-me-accompagnamento-e-ascolto-nel-lutto-e-nella-sofferenza-mentale\/\",\"url\":\"https:\/\/www.diocesi.torino.it\/salute\/lu-me-accompagnamento-e-ascolto-nel-lutto-e-nella-sofferenza-mentale\/\",\"name\":\"Lu.Me. Accompagnamento e Ascolto nel Lutto e nella Sofferenza Mentale - Pastorale della SALUTE\",\"isPartOf\":{\"@id\":\"https:\/\/www.diocesi.torino.it\/salute\/#website\"},\"datePublished\":\"2026-05-27T08:56:22+00:00\",\"dateModified\":\"2026-07-08T07:27:22+00:00\",\"author\":{\"@id\":\"https:\/\/www.diocesi.torino.it\/salute\/#\/schema\/person\/e2c61948923a2a13263c30dcbabf1603\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.diocesi.torino.it\/salute\/lu-me-accompagnamento-e-ascolto-nel-lutto-e-nella-sofferenza-mentale\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.diocesi.torino.it\/salute\/lu-me-accompagnamento-e-ascolto-nel-lutto-e-nella-sofferenza-mentale\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.diocesi.torino.it\/salute\/lu-me-accompagnamento-e-ascolto-nel-lutto-e-nella-sofferenza-mentale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.diocesi.torino.it\/salute\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lu.Me. Accompagnamento e Ascolto nel Lutto e nella Sofferenza Mentale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.diocesi.torino.it\/salute\/#website\",\"url\":\"https:\/\/www.diocesi.torino.it\/salute\/\",\"name\":\"Pastorale della SALUTE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.diocesi.torino.it\/salute\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.diocesi.torino.it\/salute\/#\/schema\/person\/e2c61948923a2a13263c30dcbabf1603\",\"name\":\"ivanraimondi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.diocesi.torino.it\/salute\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0ff803090d0fdccca5229bfcdd1b40dd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0ff803090d0fdccca5229bfcdd1b40dd?s=96&d=mm&r=g\",\"caption\":\"ivanraimondi\"},\"url\":\"https:\/\/www.diocesi.torino.it\/salute\/author\/ivanraimondi\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lu.Me. Accompagnamento e Ascolto nel Lutto e nella Sofferenza Mentale - Pastorale della SALUTE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diocesi.torino.it\/salute\/lu-me-accompagnamento-e-ascolto-nel-lutto-e-nella-sofferenza-mentale\/","og_locale":"it_IT","og_type":"article","og_title":"Lu.Me. Accompagnamento e Ascolto nel Lutto e nella Sofferenza Mentale - Pastorale della SALUTE","og_description":"Sono due i servizi realizzati in collaborazione con i Tavoli diocesani per la pastorale del lutto e per la salute mentale. Accompagnamento ed Ascolto nel lutto Il servizio \u00e8 rivolto a tutti coloro che affrontano situazioni di lutto e che necessitano di qualche forma di aiuto e supporto relazionale per elaborare la perdita e superare le fasi pi\u00f9 acute di sofferenza. Il servizio propone attivit\u00e0 &hellip; Continua a leggere &raquo;","og_url":"https:\/\/www.diocesi.torino.it\/salute\/lu-me-accompagnamento-e-ascolto-nel-lutto-e-nella-sofferenza-mentale\/","og_site_name":"Pastorale della SALUTE","article_published_time":"2026-05-27T08:56:22+00:00","article_modified_time":"2026-07-08T07:27:22+00:00","og_image":[{"width":270,"height":270,"url":"https:\/\/www.diocesi.torino.it\/salute\/wp-content\/uploads\/sites\/9\/2017\/09\/Lume.jpg","type":"image\/jpeg"}],"author":"ivanraimondi","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ivanraimondi","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.diocesi.torino.it\/salute\/lu-me-accompagnamento-e-ascolto-nel-lutto-e-nella-sofferenza-mentale\/","url":"https:\/\/www.diocesi.torino.it\/salute\/lu-me-accompagnamento-e-ascolto-nel-lutto-e-nella-sofferenza-mentale\/","name":"Lu.Me. Accompagnamento e Ascolto nel Lutto e nella Sofferenza Mentale - Pastorale della SALUTE","isPartOf":{"@id":"https:\/\/www.diocesi.torino.it\/salute\/#website"},"datePublished":"2026-05-27T08:56:22+00:00","dateModified":"2026-07-08T07:27:22+00:00","author":{"@id":"https:\/\/www.diocesi.torino.it\/salute\/#\/schema\/person\/e2c61948923a2a13263c30dcbabf1603"},"breadcrumb":{"@id":"https:\/\/www.diocesi.torino.it\/salute\/lu-me-accompagnamento-e-ascolto-nel-lutto-e-nella-sofferenza-mentale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diocesi.torino.it\/salute\/lu-me-accompagnamento-e-ascolto-nel-lutto-e-nella-sofferenza-mentale\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.diocesi.torino.it\/salute\/lu-me-accompagnamento-e-ascolto-nel-lutto-e-nella-sofferenza-mentale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.diocesi.torino.it\/salute\/"},{"@type":"ListItem","position":2,"name":"Lu.Me. Accompagnamento e Ascolto nel Lutto e nella Sofferenza Mentale"}]},{"@type":"WebSite","@id":"https:\/\/www.diocesi.torino.it\/salute\/#website","url":"https:\/\/www.diocesi.torino.it\/salute\/","name":"Pastorale della SALUTE","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diocesi.torino.it\/salute\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.diocesi.torino.it\/salute\/#\/schema\/person\/e2c61948923a2a13263c30dcbabf1603","name":"ivanraimondi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.diocesi.torino.it\/salute\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0ff803090d0fdccca5229bfcdd1b40dd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0ff803090d0fdccca5229bfcdd1b40dd?s=96&d=mm&r=g","caption":"ivanraimondi"},"url":"https:\/\/www.diocesi.torino.it\/salute\/author\/ivanraimondi\/"}]}},"_links":{"self":[{"href":"https:\/\/www.diocesi.torino.it\/salute\/wp-json\/wp\/v2\/posts\/4967"}],"collection":[{"href":"https:\/\/www.diocesi.torino.it\/salute\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diocesi.torino.it\/salute\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diocesi.torino.it\/salute\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diocesi.torino.it\/salute\/wp-json\/wp\/v2\/comments?post=4967"}],"version-history":[{"count":3,"href":"https:\/\/www.diocesi.torino.it\/salute\/wp-json\/wp\/v2\/posts\/4967\/revisions"}],"predecessor-version":[{"id":5623,"href":"https:\/\/www.diocesi.torino.it\/salute\/wp-json\/wp\/v2\/posts\/4967\/revisions\/5623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diocesi.torino.it\/salute\/wp-json\/wp\/v2\/media\/1318"}],"wp:attachment":[{"href":"https:\/\/www.diocesi.torino.it\/salute\/wp-json\/wp\/v2\/media?parent=4967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diocesi.torino.it\/salute\/wp-json\/wp\/v2\/categories?post=4967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diocesi.torino.it\/salute\/wp-json\/wp\/v2\/tags?post=4967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}