{"id":4365,"date":"2020-09-28T17:32:20","date_gmt":"2020-09-28T15:32:20","guid":{"rendered":"http:\/\/www.diocesi.torino.it\/scuola\/?p=4365"},"modified":"2020-10-03T15:40:39","modified_gmt":"2020-10-03T13:40:39","slug":"messaggio-dellarcivescovo-per-linizio-della-s-2020-21","status":"publish","type":"post","link":"https:\/\/www.diocesi.torino.it\/scuola\/2020\/09\/28\/messaggio-dellarcivescovo-per-linizio-della-s-2020-21\/","title":{"rendered":"Messaggio dell&#8217;Arcivescovo per l&#8217;inizio dell&#8217;A.S. 2020\/21"},"content":{"rendered":"<p>Carissime\/i Insegnanti,<\/p>\n<p>\u00e8 stato pubblicato il messaggio augurale dell&#8217;Arcivescovo di Torino, S.E. Mons. Cesare Nosiglia, in occasione dell&#8217;inizio del nuovo Anno Scolastico 2020\/21.<\/p>\n<p>Partendo dalla particolare situazione di questo periodo, il messaggio verte sul concetto di &#8220;alleanza educativa&#8221; tra tutti i soggetti che a diverso titolo hanno a che fare con questo settore: dalla scuola, alle famiglie, agli oratori, senza dimenticare le Associazioni sportive e culturali, i Comuni e pi\u00f9 in generale il &#8220;terzo settore&#8221;.<\/p>\n<p>L&#8217;auspicio \u00e8 quello di poter riuscire a costituire, finalmente tutti insieme, un terreno fecondo per lo sviluppo delle nuove generazioni. Le esperienze concrete di dialogo, condivisione, accoglienza\u00a0 che la scuola pu\u00f2 promuovere incentiveranno la crescita dei ragazzi nella convivenza democratica, nella cittadinanza attiva e nella partecipazione.<\/p>\n<p>Troverete il testo integrale del messaggio in due differenti formati allegati qui di seguito: il formato &#8220;Stampa&#8221; pi\u00f9 adatto alla diffusione cartacea o lettura su PC e il formato &#8220;Smartphone&#8221; pensato per essere diffuso e letto direttamente dal cellulare.<\/p>\n<hr class=\"wpba_attachment_hr\"><div id='wpba_attachment_list' class='wpba wpba-wrap'>\n<ul class='wpba-attachment-list unstyled'><li id='wpba_attachment_list_4367' class='wpba-list-item pull-left'><img src='https:\/\/www.diocesi.torino.it\/scuola\/wp-content\/themes\/wp-starter-so\/icons\/document.png' width='16' height='20' class='wpba-icon pull-left'><a href='https:\/\/www.diocesi.torino.it\/scuola\/wp-content\/uploads\/sites\/18\/2020\/09\/Messaggio-Vescovo-SCUOLA-Locandina-2020-2021.pdf' title='Messaggio dell&#039;Arcivescovo SCUOLA Stampa 2020-2021' class='wpba-link pull-left' target=\"_blank\">Messaggio dell&#039;Arcivescovo SCUOLA Stampa 2020-2021<\/a><\/li>\n<\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Carissime\/i Insegnanti, \u00e8 stato pubblicato il messaggio augurale dell&#8217;Arcivescovo di Torino, S.E. Mons. Cesare Nosiglia, in occasione dell&#8217;inizio del nuovo Anno Scolastico 2020\/21. Partendo dalla particolare situazione di questo periodo, il messaggio verte sul concetto di &#8220;alleanza educativa&#8221; tra tutti i soggetti che a diverso titolo hanno a che fare con questo settore: dalla scuola, alle famiglie, agli oratori, senza dimenticare le Associazioni sportive e &hellip; <a href=\"https:\/\/www.diocesi.torino.it\/scuola\/2020\/09\/28\/messaggio-dellarcivescovo-per-linizio-della-s-2020-21\/\" class=\"more-link\">Continua a leggere <span class=\"screen-reader-text\"><\/span> <span class=\"meta-nav\">&raquo;<\/span><\/a><\/p>\n","protected":false},"author":27,"featured_media":4369,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ip_address":"","user_agent":"","level":"","revision":"","cookie_id":"","page_referer":"","html_form":"","_expiration-date-status":"saved","_expiration-date":0,"_expiration-date-type":"","_expiration-date-categories":[],"_expiration-date-options":[]},"categories":[104,1,105],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Messaggio dell&#039;Arcivescovo per l&#039;inizio dell&#039;A.S. 2020\/21 - Pastorale SCOLASTICA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diocesi.torino.it\/scuola\/2020\/09\/28\/messaggio-dellarcivescovo-per-linizio-della-s-2020-21\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Messaggio dell&#039;Arcivescovo per l&#039;inizio dell&#039;A.S. 2020\/21 - Pastorale SCOLASTICA\" \/>\n<meta property=\"og:description\" content=\"Carissime\/i Insegnanti, \u00e8 stato pubblicato il messaggio augurale dell&#8217;Arcivescovo di Torino, S.E. Mons. Cesare Nosiglia, in occasione dell&#8217;inizio del nuovo Anno Scolastico 2020\/21. Partendo dalla particolare situazione di questo periodo, il messaggio verte sul concetto di &#8220;alleanza educativa&#8221; tra tutti i soggetti che a diverso titolo hanno a che fare con questo settore: dalla scuola, alle famiglie, agli oratori, senza dimenticare le Associazioni sportive e &hellip; Continua a leggere &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diocesi.torino.it\/scuola\/2020\/09\/28\/messaggio-dellarcivescovo-per-linizio-della-s-2020-21\/\" \/>\n<meta property=\"og:site_name\" content=\"Pastorale SCOLASTICA\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-28T15:32:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-03T13:40:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diocesi.torino.it\/scuola\/wp-content\/uploads\/sites\/18\/2020\/09\/ritornoscuola.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"299\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"abertolazzi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"abertolazzi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.diocesi.torino.it\/scuola\/2020\/09\/28\/messaggio-dellarcivescovo-per-linizio-della-s-2020-21\/\",\"url\":\"https:\/\/www.diocesi.torino.it\/scuola\/2020\/09\/28\/messaggio-dellarcivescovo-per-linizio-della-s-2020-21\/\",\"name\":\"Messaggio dell'Arcivescovo per l'inizio dell'A.S. 2020\/21 - Pastorale SCOLASTICA\",\"isPartOf\":{\"@id\":\"https:\/\/www.diocesi.torino.it\/scuola\/#website\"},\"datePublished\":\"2020-09-28T15:32:20+00:00\",\"dateModified\":\"2020-10-03T13:40:39+00:00\",\"author\":{\"@id\":\"https:\/\/www.diocesi.torino.it\/scuola\/#\/schema\/person\/0f718632ce90379c4d6b47f54c065dfd\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.diocesi.torino.it\/scuola\/2020\/09\/28\/messaggio-dellarcivescovo-per-linizio-della-s-2020-21\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.diocesi.torino.it\/scuola\/2020\/09\/28\/messaggio-dellarcivescovo-per-linizio-della-s-2020-21\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.diocesi.torino.it\/scuola\/2020\/09\/28\/messaggio-dellarcivescovo-per-linizio-della-s-2020-21\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.diocesi.torino.it\/scuola\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Messaggio dell&#8217;Arcivescovo per l&#8217;inizio dell&#8217;A.S. 2020\/21\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.diocesi.torino.it\/scuola\/#website\",\"url\":\"https:\/\/www.diocesi.torino.it\/scuola\/\",\"name\":\"Pastorale SCOLASTICA\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.diocesi.torino.it\/scuola\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.diocesi.torino.it\/scuola\/#\/schema\/person\/0f718632ce90379c4d6b47f54c065dfd\",\"name\":\"abertolazzi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.diocesi.torino.it\/scuola\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/972a5441d5f639f8f9cd48b7fd717b76?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/972a5441d5f639f8f9cd48b7fd717b76?s=96&d=mm&r=g\",\"caption\":\"abertolazzi\"},\"url\":\"https:\/\/www.diocesi.torino.it\/scuola\/author\/abertolazzi\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Messaggio dell'Arcivescovo per l'inizio dell'A.S. 2020\/21 - Pastorale SCOLASTICA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diocesi.torino.it\/scuola\/2020\/09\/28\/messaggio-dellarcivescovo-per-linizio-della-s-2020-21\/","og_locale":"it_IT","og_type":"article","og_title":"Messaggio dell'Arcivescovo per l'inizio dell'A.S. 2020\/21 - Pastorale SCOLASTICA","og_description":"Carissime\/i Insegnanti, \u00e8 stato pubblicato il messaggio augurale dell&#8217;Arcivescovo di Torino, S.E. Mons. Cesare Nosiglia, in occasione dell&#8217;inizio del nuovo Anno Scolastico 2020\/21. Partendo dalla particolare situazione di questo periodo, il messaggio verte sul concetto di &#8220;alleanza educativa&#8221; tra tutti i soggetti che a diverso titolo hanno a che fare con questo settore: dalla scuola, alle famiglie, agli oratori, senza dimenticare le Associazioni sportive e &hellip; Continua a leggere &raquo;","og_url":"https:\/\/www.diocesi.torino.it\/scuola\/2020\/09\/28\/messaggio-dellarcivescovo-per-linizio-della-s-2020-21\/","og_site_name":"Pastorale SCOLASTICA","article_published_time":"2020-09-28T15:32:20+00:00","article_modified_time":"2020-10-03T13:40:39+00:00","og_image":[{"width":299,"height":168,"url":"https:\/\/www.diocesi.torino.it\/scuola\/wp-content\/uploads\/sites\/18\/2020\/09\/ritornoscuola.jpg","type":"image\/jpeg"}],"author":"abertolazzi","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"abertolazzi","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.diocesi.torino.it\/scuola\/2020\/09\/28\/messaggio-dellarcivescovo-per-linizio-della-s-2020-21\/","url":"https:\/\/www.diocesi.torino.it\/scuola\/2020\/09\/28\/messaggio-dellarcivescovo-per-linizio-della-s-2020-21\/","name":"Messaggio dell'Arcivescovo per l'inizio dell'A.S. 2020\/21 - Pastorale SCOLASTICA","isPartOf":{"@id":"https:\/\/www.diocesi.torino.it\/scuola\/#website"},"datePublished":"2020-09-28T15:32:20+00:00","dateModified":"2020-10-03T13:40:39+00:00","author":{"@id":"https:\/\/www.diocesi.torino.it\/scuola\/#\/schema\/person\/0f718632ce90379c4d6b47f54c065dfd"},"breadcrumb":{"@id":"https:\/\/www.diocesi.torino.it\/scuola\/2020\/09\/28\/messaggio-dellarcivescovo-per-linizio-della-s-2020-21\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diocesi.torino.it\/scuola\/2020\/09\/28\/messaggio-dellarcivescovo-per-linizio-della-s-2020-21\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.diocesi.torino.it\/scuola\/2020\/09\/28\/messaggio-dellarcivescovo-per-linizio-della-s-2020-21\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.diocesi.torino.it\/scuola\/"},{"@type":"ListItem","position":2,"name":"Messaggio dell&#8217;Arcivescovo per l&#8217;inizio dell&#8217;A.S. 2020\/21"}]},{"@type":"WebSite","@id":"https:\/\/www.diocesi.torino.it\/scuola\/#website","url":"https:\/\/www.diocesi.torino.it\/scuola\/","name":"Pastorale SCOLASTICA","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diocesi.torino.it\/scuola\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.diocesi.torino.it\/scuola\/#\/schema\/person\/0f718632ce90379c4d6b47f54c065dfd","name":"abertolazzi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.diocesi.torino.it\/scuola\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/972a5441d5f639f8f9cd48b7fd717b76?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/972a5441d5f639f8f9cd48b7fd717b76?s=96&d=mm&r=g","caption":"abertolazzi"},"url":"https:\/\/www.diocesi.torino.it\/scuola\/author\/abertolazzi\/"}]}},"_links":{"self":[{"href":"https:\/\/www.diocesi.torino.it\/scuola\/wp-json\/wp\/v2\/posts\/4365"}],"collection":[{"href":"https:\/\/www.diocesi.torino.it\/scuola\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diocesi.torino.it\/scuola\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diocesi.torino.it\/scuola\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diocesi.torino.it\/scuola\/wp-json\/wp\/v2\/comments?post=4365"}],"version-history":[{"count":10,"href":"https:\/\/www.diocesi.torino.it\/scuola\/wp-json\/wp\/v2\/posts\/4365\/revisions"}],"predecessor-version":[{"id":4383,"href":"https:\/\/www.diocesi.torino.it\/scuola\/wp-json\/wp\/v2\/posts\/4365\/revisions\/4383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diocesi.torino.it\/scuola\/wp-json\/wp\/v2\/media\/4369"}],"wp:attachment":[{"href":"https:\/\/www.diocesi.torino.it\/scuola\/wp-json\/wp\/v2\/media?parent=4365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diocesi.torino.it\/scuola\/wp-json\/wp\/v2\/categories?post=4365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diocesi.torino.it\/scuola\/wp-json\/wp\/v2\/tags?post=4365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}