{"id":188,"date":"2024-02-12T15:10:02","date_gmt":"2024-02-12T14:10:02","guid":{"rendered":"https:\/\/www.diocesi.torino.it\/ufficiostampa\/?p=188"},"modified":"2024-02-12T15:10:02","modified_gmt":"2024-02-12T14:10:02","slug":"coro-galleria-e-scurolo-del-duomo-di-torino-fine-lavori-post-incendio-cappella-sindone","status":"publish","type":"post","link":"https:\/\/www.diocesi.torino.it\/ufficiostampa\/coro-galleria-e-scurolo-del-duomo-di-torino-fine-lavori-post-incendio-cappella-sindone\/","title":{"rendered":"CORO, GALLERIA E SCUROLO DEL DUOMO DI TORINO: FINE LAVORI POST-INCENDIO CAPPELLA SINDONE"},"content":{"rendered":"<p style=\"text-align: center;\">\n<p style=\"text-align: center;\"><strong>Presentazione del restauro a completamento dei lavori<br \/>\n<\/strong><strong>dopo l\u2019incendio della cappella della Sindone<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>VENERD\u00cc 16 FEBBRAIO 2024 &#8211; ORE 11.00<br \/>\n<\/strong><strong>PALAZZO CHIABLESE, SALONE DEGLI SVIZZERI<br \/>\n<\/strong><strong>PIAZZA SAN GIOVANNI, 2 &#8211; TORINO<\/strong><\/p>\n<p>L\u2019iniziativa congiunta tra Arcidiocesi di Torino e Ministero della Cultura, si svolger\u00e0 alla presenza dell\u2019Arcivescovo <strong>Roberto Repole<\/strong>\u00a0e del Segretario generale dott. <strong>Mario Turetta<\/strong><\/p>\n<p>Il cantiere appena concluso rappresenta l\u2019ultimo anello dei restauri che hanno ripristinato gli ambienti interessati dal devastante incendio della cappella della Sindone dell\u2019aprile 1997.<\/p>\n<p>Condotti con finanziamenti ministeriali, i lavori hanno coinvolto gli spazi posti sotto la cappella della Sindone: il cosiddetto \u2018scurolo\u2019, la galleria, ove \u00e8 stato riposizionato l\u2019eccezionale fondale scenografico dipinto da Domenico Guidobono nel 1709, ed il coro, nel quale sono stati ricollocati gli stalli lignei rimossi a seguito dell\u2019incendio e restaurate le bifore del cleristorio.<\/p>\n<p>Oltre a rendere nuovamente fruibili luoghi di fatto inagibili dal 1997, i restauri sono stati l\u2019occasione per approfondire la conoscenza della fabbrica del Duomo rinascimentale proprio nel punto in cui il cantiere seicentesco si \u00e8 inserito con pesanti demolizioni sulle strutture precedenti.<\/p>\n<p>Il nuovo allestimento della galleria permette il dialogo armonioso tra elementi architettonici e decorativi finora sconosciuti che appartengono a epoche diverse, ora valorizzati in un percorso di scoperta e conoscenza.<\/p>\n<p>Al termine, visita dei luoghi oggetto di intervento nel Duomo di San Giovanni.<\/p>\n<p><strong><a href=\"https:\/\/www.diocesi.torino.it\/ufficiostampa\/wp-content\/uploads\/sites\/38\/2024\/02\/cs_restauro_coro_galleria_scurolo_duomo_torino_16-02-24.pdf\">QUI l\u2019invito che contiene anche l&#8217;elenco completo dei relatori<\/a>\u200b<\/strong><\/p>\n<p><em>Torino, 12 febbraio 2024<\/em><\/p>\n<hr class=\"wpba_attachment_hr\"><div id='wpba_attachment_list' class='wpba wpba-wrap'>\n<ul class='wpba-attachment-list unstyled'><li id='wpba_attachment_list_189' class='wpba-list-item pull-left'><img src='https:\/\/www.diocesi.torino.it\/ufficiostampa\/wp-content\/themes\/wp-starter-so\/icons\/document.png' width='16' height='20' class='wpba-icon pull-left'><a href='https:\/\/www.diocesi.torino.it\/ufficiostampa\/wp-content\/uploads\/sites\/38\/2024\/02\/cs_restauro_coro_galleria_scurolo_duomo_torino_16-02-24.pdf' title='cs_restauro_coro_galleria_scurolo_duomo_torino_16-02-24' class='wpba-link pull-left' target=\"_blank\">cs_restauro_coro_galleria_scurolo_duomo_torino_16-02-24<\/a><\/li>\n<\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Presentazione del restauro a completamento dei lavori dopo l\u2019incendio della cappella della Sindone VENERD\u00cc 16 FEBBRAIO 2024 &#8211; ORE 11.00 PALAZZO CHIABLESE, SALONE DEGLI SVIZZERI PIAZZA SAN GIOVANNI, 2 &#8211; TORINO L\u2019iniziativa congiunta tra Arcidiocesi di Torino e Ministero della Cultura, si svolger\u00e0 alla presenza dell\u2019Arcivescovo Roberto Repole\u00a0e del Segretario generale dott. Mario Turetta Il cantiere appena concluso rappresenta l\u2019ultimo anello dei restauri che hanno &hellip; <a href=\"https:\/\/www.diocesi.torino.it\/ufficiostampa\/coro-galleria-e-scurolo-del-duomo-di-torino-fine-lavori-post-incendio-cappella-sindone\/\" class=\"more-link\">Continua a leggere <span class=\"screen-reader-text\"><\/span> <span class=\"meta-nav\">&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ip_address":"","user_agent":"","level":"","revision":"","cookie_id":"","page_referer":"","html_form":"","_expiration-date-status":"","_expiration-date":0,"_expiration-date-type":"","_expiration-date-categories":[],"_expiration-date-options":[]},"categories":[4],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.diocesi.torino.it\/ufficiostampa\/wp-json\/wp\/v2\/posts\/188"}],"collection":[{"href":"https:\/\/www.diocesi.torino.it\/ufficiostampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diocesi.torino.it\/ufficiostampa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diocesi.torino.it\/ufficiostampa\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diocesi.torino.it\/ufficiostampa\/wp-json\/wp\/v2\/comments?post=188"}],"version-history":[{"count":1,"href":"https:\/\/www.diocesi.torino.it\/ufficiostampa\/wp-json\/wp\/v2\/posts\/188\/revisions"}],"predecessor-version":[{"id":190,"href":"https:\/\/www.diocesi.torino.it\/ufficiostampa\/wp-json\/wp\/v2\/posts\/188\/revisions\/190"}],"wp:attachment":[{"href":"https:\/\/www.diocesi.torino.it\/ufficiostampa\/wp-json\/wp\/v2\/media?parent=188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diocesi.torino.it\/ufficiostampa\/wp-json\/wp\/v2\/categories?post=188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diocesi.torino.it\/ufficiostampa\/wp-json\/wp\/v2\/tags?post=188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}